{"id":43051,"date":"2017-12-27T04:00:31","date_gmt":"2017-12-27T03:00:31","guid":{"rendered":"https:\/\/evofitness.at\/uncategorized\/tutorial-push-up-2\/"},"modified":"2017-12-27T04:00:31","modified_gmt":"2017-12-27T03:00:31","slug":"tutorial-push-up-2","status":"publish","type":"post","link":"https:\/\/evofitness.at\/de\/blog\/learn\/tutorial-push-up-2\/","title":{"rendered":"Tutorial: Suspended Push-Up"},"content":{"rendered":"<h2>WAS<\/h2>\n<p><strong>Der <span style=\"text-decoration: underline;\"><a href=\"https:\/\/vimeo.com\/194339527\/bcb11c04a1\">Suspended Push-Up<\/a><\/span> ist eine funktionelle Kraft- und Balance\u00fcbung f\u00fcr den gesamten K\u00f6rper.<\/strong><\/p>\n<ul>\n<li>F\u00fcr diese Suspended Push-up \u00dcbung brauchst du eine Stange und Halteleisten (zum Anbringen der Stange). Hier trainierst du die Brustmuskulatur, Arme, Bauchmuskeln und die Stabilisierung der Wirbels\u00e4ule.<\/li>\n<li>Eine gro\u00dfartige \u00dcbung f\u00fcr jene, die ein wenig Abwechslung in ihr Brust-Workout bringen m\u00f6chten.<\/li>\n<\/ul>\n<h2>HOW<\/h2>\n<ul>\n<li>Greife die Stange mit beiden H\u00e4nden (diese ist an den Leisten angebracht) und strecke die Arme durch. Die Stange sollte sich ca. unterhalb des Brustkorbes befinden.<\/li>\n<li>Versuche, deinen Rumpf weiterhin in einer Plank-Position zu halten, w\u00e4hrend du dich mit den Ellbogen nach au\u00dfen zeigend in Richtung Stange absenkst.<\/li>\n<li>Unten an der Stange angekommen (ca. 10 cm Abstand) dr\u00fccke dich wieder hoch bis deine Ellbogen ganz durchgestreckt sind.<\/li>\n<\/ul>\n<h2>WARUM<\/h2>\n<ul>\n<li>Suspended Push-Ups f\u00f6rdern die funktionelle Kraft, w\u00e4hrend man dabei den gesamten K\u00f6rper aktiviert.<\/li>\n<li>Die Muskeln im Oberk\u00f6rper sind normalerweise schw\u00e4cher als die des Unterk\u00f6rpers, weil wir sie heutzutage immer weniger einsetzen. Beim Push-up werden alle Muskeln im Rumpf trainiert und Schulterverletzungen vorgebeugt<\/li>\n<li>Wenn du diese \u00dcbung regelm\u00e4\u00dfig ausf\u00fchrst, f\u00f6rderst du damit eine gute K\u00f6rperhaltung und baust Kraft in der K\u00f6rpermitte auf. Au\u00dferdem verhinderst du das Auftreten von Schmerzen im unteren R\u00fccken.<\/li>\n<\/ul>\n<p><iframe loading=\"lazy\" title=\"Push up\" src=\"https:\/\/player.vimeo.com\/video\/194339527?h=bcb11c04a1&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe><\/p>\n<h4>Hat dir der Tutorial f\u00fcr den Suspended Push-Up geholfen? Hier sind noch andere Tutorials:<\/h4>\n<ul>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-mountain-climbers\/\">Mountain Climbers<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-deep-squat\/\">Deep Squat<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-trx-knee-pull\/\">TRX Knee Pull \u00dcbung<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-ubung-fur-huftbeweglichkeit\/\">H\u00fcftbeweglichkeit<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-burpee-pull-up\/\">Burpee Pull-Up \u00dcbung<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-jab-cross\/\">Jab Cross \u00dcbung<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-med-ball-chop\/\">Med Ball Chop \u00dcbung<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-lunge-forward-reach\/\">Lunge with Forward Reach<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-faszienrolle-oberer-rucken\/\">Faszienrolle f\u00fcr den Oberen R\u00fccken<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-trx-plank\/\">TRX Plank<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-uebungen-mit-der-foam-roll-fuer-die-grosse-rueckenmuskulatur\/\">Foam Roll f\u00fcr die gro\u00dfe R\u00fcckenmuskulatur<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-unterstuetzte-hip-extensions\/\">Unterst\u00fctzte Hip Extension<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-kinesis-station-step-up\/\">Kinesis Step Up \u00dcbung<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-kinesis-station-overhead-press\/\">Kinesis Overhead Press \u00dcbung<\/a><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>WAS Der Suspended Push-Up ist eine funktionelle Kraft- und Balance\u00fcbung f\u00fcr den gesamten K\u00f6rper. F\u00fcr diese Suspended Push-up \u00dcbung brauchst&#8230;<\/p>\n","protected":false},"author":4,"featured_media":43050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Tutorial: So f\u00fchrst du den Suspended Push-up korrekt aus | EVO Fitness|Tutorial: So f\u00fchrst du den Suspended Push-up korrekt aus | EVO Fitness","_seopress_titles_desc":"Der Suspended Push-Up f\u00f6rdert eine gute K\u00f6rperhaltung, baut Kraft in der K\u00f6rpermitte auf und verhinderst das Auftreten von Schmerzen im unteren R\u00fccken.|Der Suspended Push-Up f\u00f6rdert eine gute K\u00f6rperhaltung, baut Kraft in der K\u00f6rpermitte auf und verhinderst das Auftreten von Schmerzen im unteren R\u00fccken.","_seopress_robots_index":"","_seopress_analysis_target_kw":"Suspended Push-up|Suspended Push-up","footnotes":""},"categories":[101],"tags":[321,327,328,1329],"class_list":["post-43051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn","tag-korpergewicht","tag-kraft-des-oberkorpers","tag-rumpfstabilisierung","tag-push-up-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/43051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/comments?post=43051"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/43051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media\/43050"}],"wp:attachment":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media?parent=43051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/categories?post=43051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/tags?post=43051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}