{"id":43107,"date":"2018-12-12T04:00:26","date_gmt":"2018-12-12T03:00:26","guid":{"rendered":"https:\/\/evofitness.at\/uncategorized\/tutorial-burpee-pull-up\/"},"modified":"2018-12-12T04:00:26","modified_gmt":"2018-12-12T03:00:26","slug":"tutorial-burpee-pull-up","status":"publish","type":"post","link":"https:\/\/evofitness.at\/de\/blog\/learn\/tutorial-burpee-pull-up\/","title":{"rendered":"Tutorial: Burpee Pull-Up"},"content":{"rendered":"<h2>WAS<\/h2>\n<p>Der <span style=\"text-decoration: underline;\"><a href=\"https:\/\/vimeo.com\/194337534\/52d0d91144\">Burpee Pull-Up<\/a><\/span> ist eine Variante und Weiterentwicklung des beliebten klassischen Burpees. Wie der Name schon verr\u00e4t, wird bei ersterem <strong>ein Klimmzug hinzugef\u00fcgt.<\/strong><\/p>\n<ul>\n<li>Diese \u00dcbung beansprucht den gesamten K\u00f6rper, wodurch die Herzfrequenz effektiv erh\u00f6ht wird.<\/li>\n<li>Der Burpee Pull-Up ist die ideale \u00dcbung, wenn du nur wenig Zeit zum Trainieren oder Lust auf ein hochintensives Workout hast.<\/li>\n<\/ul>\n<h2>WIE<\/h2>\n<ul>\n<li>Stelle dich unter ein hohes Reck. Du kannst auch eine superfunktionelle Stange verwenden, falls es sie in deinem Club gibt. Spanne deine K\u00f6rpermitte an.<\/li>\n<li>Beuge dich in einer schnellen Bewegung und gehe dabei in die Tiefe. Setze deine H\u00e4nde vor deinen F\u00fc\u00dfen auf dem Boden ab und springe gleichzeitig mit den F\u00fc\u00dfen nach hinten, sodass du in einer Liegest\u00fctzposition landest.<\/li>\n<li>Mache eine Liegest\u00fctze und springe beim Hochkommen in eine Kniebeugeposition.<\/li>\n<li>Strecke deine Beine und springe, um die Stange zu fassen. Nutze den Sprung f\u00fcr den Klimmzug. Gehe wieder in die Ausgangsposition zur\u00fcck und wiederhole die gesamte Bewegung kontinuierlich.<\/li>\n<\/ul>\n<h2>WARUM<\/h2>\n<ul>\n<li>Der Burpee Pull-Up ist eine wunderbare Fortsetzung f\u00fcr alle, die den klassischen Burpee beherrschen und ihr Workout intensivieren m\u00f6chten, ohne die Wiederholungsanzahl zu erh\u00f6hen.<\/li>\n<li>Der Sprung zum Klimmzug ist ideal f\u00fcr diejenigen, die den Klimmzug erlernen m\u00f6chten, aber noch nicht \u00fcber ausreichend Kraft verf\u00fcgen, um sich aus dem Stand hochzuziehen. Bei einer superfunktionellen Stange kann man zudem die H\u00f6he verstellen und je nach Trainingsfortschritt h\u00f6her h\u00e4ngen.<\/li>\n<li>Jegliche Burpee Variationen bauen in kurzer Zeit Kraft und kardiovaskul\u00e4re Fitness auf \u2013 und sind daher ideal sowohl um allgemeine Fitness und athletische Leistung zu verbessern, als auch um abzunehmen.<\/li>\n<\/ul>\n<p><iframe loading=\"lazy\" title=\"Burpee pull up\" src=\"https:\/\/player.vimeo.com\/video\/194337534?h=52d0d91144&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"338\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media\"><\/iframe><\/p>\n<h4>Hat dir der Tutorial f\u00fcr den Burpee Pull-Up geholfen? Hier sind noch andere Tutorials:<\/h4>\n<ul>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-superfunctional-y\/\">Superfunctional Y<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-hanging-knee-lift\/\">Hanging Knee Lift<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-burpee\/\">Burpee<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-barbell-front-squat\/\">Barbell Front Squat<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-hamstring-curl\/\">Hamstring Curl<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-trx-low-pull\/\">TRX Low Pull<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-seitliche-sprunge\/\">Seitliche Spr\u00fcnge<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-liegestutz-mit-rotation\/\">Liegest\u00fctz mit Rotation<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-suspended-squat\/\">Suspended Squat<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-jump-pull-up\/\">Jump Pull-up<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/suspended-lunge-tutorial\/\">Suspended Lunge<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-kinesis-low-to-high-chop\/\">Kinesis Low to High Chop<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-kinesis-twisting-punches\/\">Kinesis Twisting Punches<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-kinesis-row\/\">Kinesis Row<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-kinesis-lunge\/\">Kinesis Lunge<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-roll-out-with-step\/\">Roll Out With Step<\/a><\/span><\/li>\n<li><span style=\"text-decoration: underline;\"><a href=\"https:\/\/evofitness.at\/tutorial-hip-extension\/\">Hip Extension<\/a><\/span><\/li>\n<li><a href=\"https:\/\/evofitness.at\/tutorial-hanging-twist\/\"><span style=\"text-decoration: underline;\">Hanging Twist<\/span><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>WAS Der Burpee Pull-Up ist eine Variante und Weiterentwicklung des beliebten klassischen Burpees. Wie der Name schon verr\u00e4t, wird bei&#8230;<\/p>\n","protected":false},"author":4,"featured_media":43106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"Tutorial: Ausf\u00fchrung der Burpee Pull-Up \u00dcbung | EVO Fitness","_seopress_titles_desc":"Der Burpee Pull-Up ist eine herausfordernde Ganzk\u00f6rper-\u00dcbung, die deine Herzfrequenz verbessert und Kraft und Ausdauer f\u00f6rdert.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"Burpee Pull-up","footnotes":""},"categories":[101],"tags":[127,128,131,134,391,392,393,394,395,396,1308,1316,1339,1340,1341],"class_list":["post-43107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learn","tag-ausdauer","tag-eigengewicht","tag-ganzkorpertraining","tag-kraft","tag-ganzkorperubung","tag-hochintensiv","tag-kardiovaskular","tag-klimmzug","tag-starke","tag-super-funktionell","tag-fitness-2","tag-high-intensity-2","tag-burpee-2","tag-pull-up-2","tag-funktionelle-fitness-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/43107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/comments?post=43107"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/43107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media\/43106"}],"wp:attachment":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media?parent=43107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/categories?post=43107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/tags?post=43107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}