{"id":44015,"date":"2021-08-30T03:00:00","date_gmt":"2021-08-30T01:00:00","guid":{"rendered":"https:\/\/evofitness.at\/uncategorized\/30-min-fullbody-workout-ohne-equipment\/"},"modified":"2021-08-30T03:00:00","modified_gmt":"2021-08-30T01:00:00","slug":"30-min-fullbody-workout-ohne-equipment","status":"publish","type":"post","link":"https:\/\/evofitness.at\/de\/blog\/move\/30-min-fullbody-workout-ohne-equipment\/","title":{"rendered":"Workout der Woche: 30 Min. Full-body Workout ohne Equipment"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>ALLE FITNESSLEVEL <\/strong>\/ Full-body Workout ohne Equipment \/ 30 Minuten<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ausr\u00fcstung<\/strong>: Trainingsmatte<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">EVO ist mehr als nur ein Fitnessstudio. Wir sehen uns selbst als einen <strong>Ort, der die nat\u00fcrliche menschliche Bewegung f\u00f6rdert und entwickelt<\/strong>. Verstehe uns nicht falsch: Egal, was deine Fitnessziele sind, <strong>wir haben <\/strong><a href=\"https:\/\/evofitness.at\/training\/\">alles, was du brauchst<\/a>. Dennoch stehen wir f\u00fcr einen nat\u00fcrlicheren Ansatz, der auf grundlegenden Bewegungen wie <strong>Stehen, in die Knie gehen, Gehen, Springen und Laufen<\/strong> basiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alle unsere Training Sessions sind auf diese Philosophie ausgerichtet<\/strong> und das gilt nat\u00fcrlich auch f\u00fcr das heutige Workout. Diese Session erfordert kein Equipment \u2013 Du kannst eine Trainingsmatte verwenden, wenn du m\u00f6chtest \u2013 und du brauchst minimalen Platz. <strong>Es geht nur um dich und deinen K<\/strong><strong>\u00f6<\/strong><strong>rper <\/strong>(und ist letzterer nicht eigentlich das ultimative Fitnessger\u00e4t \u00fcberhaupt?).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses <strong>F<\/strong><strong>ull-body <\/strong><strong>W<\/strong><strong>orkout<\/strong><strong> ohne Equipment<\/strong><strong> <\/strong>besteht aus <strong>4 verschiedenen \u00dcbungsgruppen<\/strong>. Jede Gruppe besteht aus <strong>2 \u00dcbungen<\/strong>. Du f\u00fchrst jede dieser Gruppen <strong>eineinhalb Minuten lang aus, bevor du zur n\u00e4chsten \u00fcbergehst<\/strong>. Nachdem du die <strong>4 Gruppen hintereinander abgeschlossen hast<\/strong>, <strong>ruhst du dich 45 Sekunden lang aktiv aus<\/strong> \u2013 einige entspannte Cross Jacks sind daf\u00fcr ideal. Das Workout endet, nachdem du <strong>insgesamt 4 Runden<\/strong> gemacht hast.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Gruppe \u2013 90 Sek.<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Burpees \u00fcber Matte &#8211; 5 Wiederholungen<\/li><li>Jumping Squat &#8211; 10 Wiederholungen<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2<\/strong><strong>. <\/strong><strong>Gruppe \u2013 90 <\/strong><strong>Sek.<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Commando Plank &#8211; 5 Wiederholungen&nbsp;<\/li><li>Squat Jacks &#8211; 10 Wiederholungen<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3<\/strong><strong>. <\/strong><strong>Gruppe \u2013 90 <\/strong><strong>Sek.<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Push-ups &#8211; 5x&nbsp;<\/li><li>Jumping Lunges &#8211; 10x<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>4<\/strong><strong>. <\/strong><strong>Gruppe \u2013 90 <\/strong><strong>Sek.<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>High Squat Jumps &#8211; 10 Wiederholungen<\/li><li>Side Plank Leg Raises &#8211; 30 Wiederholungen, 15 pro Seite<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los geht\u2019s!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><a href=\"https:\/\/evofitness.at\/de\/mitgliedschaften\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de.png\" alt=\"evo at standard sales campaign blog de\" class=\"wp-image-56820\" style=\"width:1024px\" srcset=\"https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de.png 1024w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-960x422.png 960w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-768x338.png 768w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-480x211.png 480w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-640x281.png 640w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT SETUP<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>4 Gruppen mit je 2 \u00dcbungen<\/li><li>Unterschiedliche Anzahl an Wiederholungen pro \u00dcbung<\/li><li>90 Sek. pro Gruppe<\/li><li>4 Runden<\/li><li>45 Sek. Pause zwischen den Runden<\/li><li>Dauer: 30 Minuten<\/li><\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">DU TRAINIERST ZU HAUSE? KEIN PROBLEM.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">EVO f\u00f6rdert nat\u00fcrliche Bewegung und f\u00fcr unsere Workouts, wie dieses hier, brauchst du normalerweise wenig bis gar kein Equipment und minimalen Raum, weshalb du sie \u00fcberall ausf\u00fchren kannst.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT \u00dcBUNGSLISTE<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4 Runden<\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">1. GRUPPE \u2013 90 SEK.<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">1 \u2013 BURPEES \u00dcBER MATTE<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Stelle dich parallel zur Matte hin und spanne den Rumpf an.<\/li><li>Beginne die Bewegung, indem du dich schnell beugst und die H\u00e4nde vor deinen F\u00fc\u00dfen auf dem Boden absetzt. Springe gleichzeitig mit den Beinen nach hinten, sodass du in der Liegest\u00fctz-Position landest..<\/li><li>Schwinge die H\u00fcfte in einer schnellen Bewegung nach oben und springe in den Squat.&nbsp;<\/li><li>Springe dann explosionsartig \u00fcber die Matte und komme w\u00e4hrenddessen in die aufrechte Position.&nbsp;<\/li><li>Wiederhole.&nbsp;<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/xN4gMKVufXo\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">2 \u2013 JUMPING SQUAT<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Stelle dich mit den F\u00fc\u00dfen h\u00fcftbreit auseinander hin. Spanne den Rumpf an und richte die Schultern.<\/li><li>Beuge Knie und H\u00fcfte in die Squat Position und beuge gleichzeitig die Arme.<\/li><li>Wenn du am untersten Punkt angelangt bist, strecke in einer schnellen Bewegung H\u00fcfte und Arme, sodass dein K\u00f6rper eine gerade Linie bildet und mache einen kleinen Sprung.&nbsp;<\/li><li>Halte bei der Landung den Rumpf angespannt und verliere nicht das Gleichgewicht. Beuge H\u00fcfte und Knie dabei leicht, um den Aufprall abzufedern.&nbsp;<\/li><li>Wiederhole.&nbsp;<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/63NjDBqv-hU\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2. GRUPPE \u2013 90 SEK.<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">1 \u2013 COMMANDO PLANK<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Lege eine Matte auf den Boden und gehe in die Plank Position. Das ist die Ausgangsposition.<\/li><li>Strecke deine Arme, sodass sie fast eingerastet sind. Halte diese Position f\u00fcr einen kurzen Moment.<\/li><li>Setze dann einen Unterarm nach dem anderen wieder ab und kehre in die Ausgangsposition zur\u00fcck.<\/li><li>Wiederhole.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/NSSNEDx9EJs\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">2 \u2013 SQUAT JACKS<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Beginne in der Squat Position; deine F\u00fc\u00dfe sind geschlossen und deine H\u00e4nde ber\u00fchren fast den Boden neben deinen Kn\u00f6cheln.<\/li><li>Springe explosionsartig in die weite Kniebeuge. \u00d6ffne dabei die Arme \u00fcber deinem Kopf wie bei einem Jumping Jack.&nbsp;<\/li><li>Springe wieder in den Squat: Beine geschlossen, Knie gebeugt und Arme seitlich an deinem K\u00f6rper.&nbsp;<\/li><li>Vergiss w\u00e4hrend der Bewegung nicht, den Brustkorb zu \u00f6ffnen und nach vorne zu schauen.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/YUOrjvmmuzE\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3. GRUPPE \u2013 90 SEK.<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">1 \u2013 PUSH-UPS<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Beginne in der Plank Position: deine Arme sind ausgestreckt, die Schultern \u00fcber den H\u00e4nden und dein K\u00f6rper bildet eine gerade Linie. Spanne Rumpf und Ges\u00e4\u00dfmuskeln an.<\/li><li>Achte darauf, dass die Schultern \u00fcber den Handgelenken bleiben, w\u00e4hrend du deinen K\u00f6rper so weit wie m\u00f6glich zu Boden sinken l\u00e4sst.<\/li><li>Push deinen K\u00f6rper wieder hoch und kehre in die Ausgangsposition zur\u00fcck. Wiederhole f\u00fcr die gew\u00fcnschte Anzahl an Wiederholungen oder auf Zeit.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/vudSOqE6FOI\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">2 \u2013 JUMPING LUNGES<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Stelle dich mit den F\u00fc\u00dfen h\u00fcftbreit auseinander hin, spanne den Rumpf an und richte die Schultern.<\/li><li>Springe nach oben und \u00f6ffne die Beine in den Ausfallschritt, indem du das hintere Knie in Richtung Boden sinken l\u00e4sst. Halte den Rumpf angespannt und den Oberk\u00f6rper gerade. Bewege die Arme entgegengesetzt zu den Beinen, um die Bewegung auszugleichen (falls notwendig).&nbsp;<\/li><li>Wenn du den untersten Punkt erreichst, springe explosionsartig wieder nach oben und \u00f6ffne die Beine auf der anderen Seite. Halte w\u00e4hrend der Bewegung dein Gleichgewicht und deine Position.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/l4gxV0XtxAg\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4. GRUPPE \u2013 90 SEK.&nbsp;<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">1 \u2013 HIGH SQUAT JUMPS<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 <\/strong><strong>Wiederholungen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Positioniere deine F\u00fc\u00dfe etwas weiter als deine H\u00fcfte und sinke in die Squat Position.<\/li><li>Nutze deine F\u00fc\u00dfe als Sprungfeder und springe explosiv in die H\u00f6he. Spring so hoch wie du kannst.<\/li><li>Hebe w\u00e4hrend des Sprungs deine Arme \u00dcberkopf f\u00fcr eine gr\u00f6\u00dfere Wirkung.<\/li><li>Gehe wieder in die Kniebeuge und wiederhole.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/HoduTTXbLdc\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">2 \u2013 SIDE PLANK LEG RAISES<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>30 Wiederholungen, 15 pro Seite<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Lege dich mit deiner linken K\u00f6rperh\u00e4lfte \u00fcber die Matte.&nbsp;<\/li><li>Platziere deinen linken Ellbogen auf der Matte, strecke beide Beine aus und hebe deinen gesamten K\u00f6rper vom Boden.<\/li><li>Achte darauf, dass dein Rumpf angespannt ist und dein K\u00f6rper eine gerade Linie bildet.&nbsp;<\/li><li>Hebe jetzt dein rechtes Bein h\u00f6her als deine rechte H\u00fcfte und halte die Position.&nbsp;<\/li><li>Bringe dann dein rechtes Knie und Ellbogen zusammen. Mache 15 Wiederholungen auf dieser Seite.<\/li><li>Wechsle die Seiten.<\/li><\/ul>\n\n\n\n<div class=\"youtube-container\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/4aI7VdfxMys\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Nach diesem intensiven Full-body Workout ohne Equipment, kannst du erst einmal durchatmen. Check dabei schon mal unsere anderen Workouts aus:<\/h4>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-a709cdb8-98ec-4f81-be4e-78131c06b7f4\"><li><a href=\"https:\/\/evofitness.at\/30-min-fullbody-workout\/\">30 Min. Full-Body Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/50-40-30-20-10-workout\/\">50-40-30-20-10 Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/10-min-gesaessmuskel-und-beine-workout\/\">10 Min. Ges\u00e4\u00dfmuskel und Beine Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/20-min-ganzkoerper-dumbbell-workout\/\">20 Min. Ganzk\u00f6rper Dumbbell Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/singlearm-kettlebell-circuit\/\">Single-arm Kettlebell Circuit<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/funktionelles-zirkeltraining\/\">Funktionelles Zirkeltraining<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/20-min-ganzkoerper-hiit-workout\/\">20 Min. Ganzk\u00f6rper HIIT Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/10-min-functional-cardio-workout\/\">10 Min Functional Cardio Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/25-min-funktionelles-glute-workout\/\">25 Min. funktionelles Glutes Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/funktionelles-dumbbell-unterkorper-workout\/(opens in a new tab)\">Funktionelles Dumbbell Unterk\u00f6rper Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/35-min-functional-full-body-workout\/\">35 Min. Functional Full-Body Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/20-min-stability-workout\/\">20 Min. Stability Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/20-min-abs-und-core-workout\/\">20 Min. Abs und Core Workout<\/a><\/li><li><a href=\"https:\/\/evofitness.at\/30-min-total-core-workout\/\">30 Min. Total Core Workout<\/a><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/linktr.ee\/evofitness_austria\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1125\" src=\"https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-scaled.png\" alt=\"blog banners follow us evo blog de\" class=\"wp-image-57964\" style=\"width:1024px\" srcset=\"https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-scaled.png 2560w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-960x422.png 960w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-1920x844.png 1920w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-768x338.png 768w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-1536x675.png 1536w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-2048x900.png 2048w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-480x211.png 480w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-640x281.png 640w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-720x316.png 720w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-1160x510.png 1160w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/blog-banners-follow-us_evo-blog_de-1440x633.png 1440w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ALLE FITNESSLEVEL \/ Full-body Workout ohne Equipment \/ 30 Minuten Ausr\u00fcstung: Trainingsmatte EVO ist mehr als nur ein Fitnessstudio. Wir&#8230;<\/p>\n","protected":false},"author":4,"featured_media":43840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"30 Min. Full-body Workout ohne Equipment | EVO Fitness","_seopress_titles_desc":"EVO f\u00f6rdert nat\u00fcrliche Bewegung und f\u00fcr unsere Workouts brauchst du wenig bis kein Equipment: Hier ist ein Full-body Workout ohne Equipment als Beweis.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"Full-body Workout ohne Equipment","footnotes":""},"categories":[102],"tags":[952,1022,1307,1458],"class_list":["post-44015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-move","tag-workout-der-woche","tag-ohne-gerate","tag-workout-2","tag-full-body-workout-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/44015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/comments?post=44015"}],"version-history":[{"count":0,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/44015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media\/43840"}],"wp:attachment":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media?parent=44015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/categories?post=44015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/tags?post=44015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}