{"id":55575,"date":"2025-07-21T05:00:00","date_gmt":"2025-07-21T03:00:00","guid":{"rendered":"https:\/\/evofitness.at\/?p=55575"},"modified":"2025-07-18T20:59:00","modified_gmt":"2025-07-18T18:59:00","slug":"100-reps-dumbbell-kraft-workout","status":"publish","type":"post","link":"https:\/\/evofitness.at\/de\/blog\/move\/100-reps-dumbbell-kraft-workout\/","title":{"rendered":"100 Reps Dumbbell-Kraft-Workout"},"content":{"rendered":"\n<p><strong>ALLE FITNESSLEVEL<\/strong>\/100 Reps Dumbbell-Kraft-Workout\/30 Minuten<\/p>\n\n\n\n<p><strong>Ausr\u00fcstung<\/strong>: Dumbbells &amp; Trainingsmatte<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>100 Wiederholungen? <\/strong>Das ist keine Zahl, die man normalerweise in einem Trainingsplan sieht \u2013 und genau das ist der Sinn der Sache. Dieses Workout stellt das klassische Trainingsskript auf den Kopf. <strong>Anstelle der \u00fcblichen S\u00e4tze, Wiederholungen und Ruhepausen erwartet dich eine Ganzk\u00f6rper-Challenge, die ebenso effektiv wie unterhaltsam ist<\/strong>. Da du dich auf die 100 Wiederholungen fokussierst, h\u00e4lt dieses Workout deinen K\u00f6rper und deinen Geist voll auf Trab, w\u00e4hrend du dieser magischen, befriedigend runden Zahl hinterherjagst.<\/p>\n\n\n\n<p>Dieses <strong>100 Reps Dumbbell-Kraft-Workout<\/strong> umfasst <strong>4 \u00dcbungen plus 1<\/strong>. Deine Mission? Absolviere <strong>100 Wiederholungen von jeder der ersten 4 \u00dcbungen<\/strong> \u2013 und das in <strong>unter 30 Minuten<\/strong>. Keine Panik \u2013 du musst nicht 100 Wiederholungen am St\u00fcck machen. Teile sie dir ein, wie du magst: 10, 15 oder \u2013 wenn du ganz abenteuerlich unterwegs bist \u2013 sogar 25 Wiederholungen. Aber hier ist der Haken: <strong>Jedes Mal, wenn du zu einer neuen \u00dcbung wechselst, sind 10 Burpees f\u00e4llig.<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Dumbbell Push Press<\/li>\n\n\n\n<li>Dumbbell Row<\/li>\n\n\n\n<li>Dumbbell Swing<\/li>\n\n\n\n<li>Dumbbell Deadlift<\/li>\n\n\n\n<li>Burpees<\/li>\n<\/ol>\n\n\n\n<p><strong>Bereit? Lass uns die 100 knacken!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized is-style-default\"><a href=\"https:\/\/evofitness.at\/de\/mitgliedschaften\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de.png\" alt=\"evo at standard sales campaign blog de\" class=\"wp-image-56820\" style=\"width:1024px\" srcset=\"https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de.png 1024w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-960x422.png 960w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-768x338.png 768w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-480x211.png 480w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-640x281.png 640w, https:\/\/evofitness.at\/wp-content\/uploads\/2019\/07\/evo-at-standard-sales-campaign-blog-de-720x316.png 720w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT SETUP<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>5 \u00dcbungen<\/li>\n\n\n\n<li>100 Wiederholungen von jeder der ersten 4 \u00dcbungen, in beliebiger Reihenfolge<\/li>\n\n\n\n<li>10 Burpees bei jedem \u00dcbungswechsel<\/li>\n\n\n\n<li>Dauer: 30 Minuten<\/li>\n\n\n\n<li>Ausr\u00fcstung: Dumbbells &amp; Trainingsmatte<\/li>\n<\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">WORKOUT \u00dcBUNGSLISTE<\/h2>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">1 &#8211; DUMBBELL PUSH-PRESS<\/h3>\n\n\n\n<p><strong>100 <\/strong><strong>Wiederholungen<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Stehe aufrecht, mit den F\u00fc\u00dfen schulterbreit auseinander und halte in jeder Hand eine Dumbbell auf Schulterh\u00f6he. Die Handfl\u00e4chen zeigen zueinander, die Ellbogen leicht nach vorn.<\/li>\n\n\n\n<li>Spanne deine K\u00f6rpermitte an und beuge leicht die Knie. Kein tiefer Squat \u2013 nur ein kurzes Absenken, um die Beine bereitzumachen.<\/li>\n\n\n\n<li>Dr\u00fccke dich explosiv durch die F\u00fc\u00dfe nach oben ab und strecke die Beine, w\u00e4hrend du die Dumbbells in einer flie\u00dfenden Bewegung \u00fcber den Kopf dr\u00fcckst. Strecke die Arme am Ende der Bewegung vollst\u00e4ndig durch.<\/li>\n\n\n\n<li>Senke die Dumbbells kontrolliert wieder auf Schulterh\u00f6he ab.<\/li>\n\n\n\n<li>Wiederhole.<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/5JievwCZ-JQ?si=moo4b_uflxrDfZiN\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> \n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; DUMBBELL ROW\u00a0\u00a0<\/h3>\n\n\n\n<p><strong>100 <\/strong><strong>Wiederholungen<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Stelle dich aufrecht hin, mit einer Dumbbell in jeder Hand. Die Handfl\u00e4chen zeigen zueinander.<\/li>\n\n\n\n<li>Beuge dich aus der H\u00fcfte nach vorn, bis dein Oberk\u00f6rper fast parallel zum Boden ist. Halte dabei den Rumpf angespannt und den R\u00fccken gerade.<\/li>\n\n\n\n<li>Zieh die Ellbogen nach hinten, w\u00e4hrend du die Schulterbl\u00e4tter fest zusammenziehst und die Dumbbells in Richtung Rippen f\u00fchrst.<\/li>\n\n\n\n<li>Halte oben kurz inne und senke dann die Gewichte kontrolliert ab.<\/li>\n\n\n\n<li>Wiederhole.<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/uezcqSCDXkw?si=hbhSLCqbGSjZezNh\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> \n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; DUMBBELL SWING<\/h3>\n\n\n\n<p><strong>100 <\/strong><strong>Wiederholungen<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Halte eine Dumbbell mit beiden H\u00e4nden \u2013 eine Hand \u00fcber der anderen \u2013 und stelle dich schulterbreit hin.<\/li>\n\n\n\n<li>Beuge leicht die Knie, schiebe die H\u00fcfte nach hinten und schwinge die Dumbbell zwischen deinen Beinen hindurch. Halte den R\u00fccken gerade und deine K\u00f6rpermitte angespannt.<\/li>\n\n\n\n<li>Bewege nun deine H\u00fcfte kraftvoll nach vorne, indem du deine Ges\u00e4\u00dfmuskeln und deine H\u00fcfte einsetzt.<\/li>\n\n\n\n<li>Spanne oben deine Rumpfmuskulatur, dein Ges\u00e4\u00df und deine Quads an.<\/li>\n\n\n\n<li>Lasse die Dumbbell kontrolliert wieder zur\u00fcckschwingen und wiederhole.<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/BVsCYSCMkUI?si=wegqL6dBBLfflWDI\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> \n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; DUMBBELL DEADLIFT<\/h3>\n\n\n\n<p><strong>100 <\/strong><strong>Wiederholungen<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Stehe aufrecht, die F\u00fc\u00dfe h\u00fcftbreit auseinander und halte in jeder Hand eine Dumbbell. Spanne deine K\u00f6rpermitte an und fixiere die Schultern.<\/li>\n\n\n\n<li>Beuge die Knie leicht und kippe aus der H\u00fcfte nach vorn, w\u00e4hrend du die H\u00fcfte nach hinten schiebst und die Dumbbells an den Beinen entlang nach unten f\u00fchrst.<\/li>\n\n\n\n<li>Halte w\u00e4hrend der gesamten Bewegung den R\u00fccken flach und die Brust aufrecht.<\/li>\n\n\n\n<li>Senke die Gewichte, bis du eine Dehnung in den hinteren Oberschenkeln sp\u00fcrst \u2013 oder bis die Dumbbells etwa auf Schienbein-H\u00f6he sind. Achte darauf, dass du deinen unteren R\u00fccken nicht rund machst.<\/li>\n\n\n\n<li>Dr\u00fccke dich durch die Fersen nach oben, spanne die Ges\u00e4\u00dfmuskulatur an und schiebe die H\u00fcfte nach vorn, um in die Ausgangsposition zur\u00fcckzukehren.<\/li>\n\n\n\n<li>Wiederhole.<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/B2GQiTIp6G0?si=_om4clOjYwbqg9tO\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> \n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">5 &#8211; BURPEES<\/h3>\n\n\n\n<p><strong>100 <\/strong><strong>Wiederholungen<\/strong>&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Beginne aufrecht stehend und spanne deine K\u00f6rpermitte an.<\/li>\n\n\n\n<li>Beginne die Bewegung, indem du dich schnell nach unten beugst und die H\u00e4nde vor deinen F\u00fc\u00dfen auf dem Boden aufsetzt. Springe gleichzeitig mit den F\u00fc\u00dfen nach hinten und lande in der Liegest\u00fctz-Position.<\/li>\n\n\n\n<li>Mache einen Liegest\u00fctz. Komme mit einem schnellen Schwung aus der H\u00fcfte wieder nach oben und lande in der Squat-Position.<\/li>\n\n\n\n<li>Kehre wieder in die aufrechte Position zur\u00fcck und wiederhole auf Zeit oder die gew\u00fcnschte Wiederholungsanzahl.<\/li>\n<\/ul>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/LzEnUI2Ignk?si=-Li1tXOsp8qurGQG\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> \n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Weitere aufregende Challenges wie dieses 100 Reps Dumbbell-Kraft-Workout findest du hier:<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/ganzkoerper-workout-auf-zeit\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ganzk\u00f6rper-Workout auf Zeit<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/30-min-schulter-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">30 Min. Schulter-Kraft-Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/unkategorisiert\/40-min-ruecken-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">40 Min. R\u00fccken-Kraft-Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/15-min-dumbbell-emom-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">15 Min. Dumbbell-EMOM- Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/25-min-pull-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">25 Min. Pull-Kraft-Workout<\/a>\u00a0\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/35-min-superset-push-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">35 Min. Superset-Push-Kraft-Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/45-min-unterkoerper-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">45 Min. Unterk\u00f6rper-Kraft-Workout\u00a0<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/30-min-oberkoerper-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">30 Min. Oberk\u00f6rper-Kraft-Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/workout-der-woche-18-min-unterkoerper-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">18 Min. Unterk\u00f6rper-Kraft-Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/20-min-ausdauer-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">20 Min. Ausdauer-Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/25-min-push-und-pull-kraft-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">25 Min. Push-und-Pull-Kraft-Workout<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/evofitness.at\/de\/blog\/move\/15-min-stoffwechsel-workout\/\" target=\"_blank\" rel=\"noreferrer noopener\">15 Min. Stoffwechsel-Kraft-Workout<\/a>\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.instagram.com\/evofitness_austria\/\"><img decoding=\"async\" src=\"https:\/\/evofitness.at\/wp-content\/uploads\/2023\/09\/evo-at-blog_de-1-1.jpg\" alt=\"Blog CTA - Instagram\" class=\"wp-image-46823\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>ALLE FITNESSLEVEL\/100 Reps Dumbbell-Kraft-Workout\/30 Minuten Ausr\u00fcstung: Dumbbells &amp; Trainingsmatte 100 Wiederholungen? Das ist keine Zahl, die man normalerweise in einem&#8230;<\/p>\n","protected":false},"author":5,"featured_media":55569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Workout der Woche: 100 Reps Dumbbell-Kraft-Workout | %%sitetitle%%","_seopress_titles_desc":"Dieses 100 Reps Dumbbell-Kraft-Workout ist keine gew\u00f6hnliche Routine - und genau das ist der Punkt. Bist du bereit, die Challenge anzunehmen?","_seopress_robots_index":"","_seopress_analysis_target_kw":"100 Reps Dumbbell-Kraft-Workout","footnotes":""},"categories":[102],"tags":[952,1037,1307,1443,1450,1462,1564],"class_list":["post-55575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-move","tag-workout-der-woche","tag-100-wiederholungen","tag-workout-2","tag-wow-2","tag-dumbbell-workout-2","tag-workout-of-the-week-2","tag-kurzhantel-workout"],"acf":[],"_links":{"self":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/55575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/comments?post=55575"}],"version-history":[{"count":2,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/55575\/revisions"}],"predecessor-version":[{"id":55603,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/posts\/55575\/revisions\/55603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media\/55569"}],"wp:attachment":[{"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/media?parent=55575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/categories?post=55575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evofitness.at\/de\/wp-json\/wp\/v2\/tags?post=55575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}